{"id":2019,"date":"2026-05-13T11:48:17","date_gmt":"2026-05-13T09:48:17","guid":{"rendered":"https:\/\/www.lebenshilfe-ohz.de\/?p=2019"},"modified":"2026-05-13T12:04:17","modified_gmt":"2026-05-13T10:04:17","slug":"wir-sind-beim-stadtradeln-dabei","status":"publish","type":"post","link":"https:\/\/www.lebenshilfe-ohz.de\/leicht\/wir-sind-beim-stadtradeln-dabei\/","title":{"rendered":"Wir sind beim STADTRADELN dabei!"},"content":{"rendered":"<section class=\"l-section wpb_row height_custom\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p>Auch in diesem Jahr macht die Lebenshilfe Osterholz wieder beim <strong>STADTRADELN<\/strong> mit \u2013 f\u00fcr mehr Klimaschutz, bessere Gesundheit und eine starke Gemeinschaft!<\/p>\n<p>Gemeinsam sammeln wir Kilometer auf dem Fahrrad und setzen ein Zeichen f\u00fcr nachhaltige Mobilit\u00e4t. Jeder geradelte Kilometer z\u00e4hlt \u2013 egal ob auf dem Weg zur Arbeit, in der Freizeit oder bei gemeinsamen Aktionen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-separator size_medium\"><\/div><div class=\"w-html us_custom_eb849559\"><div style=\"width: auto !important; min-width: 375px; max-width: 415px; height: 415px;\">\n <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PGlmcmFtZSBzdHlsZT0id2lkdGg6IDEwMCU7IGhlaWdodDogMTAwJTsiIGZyYW1lYm9yZGVyPSIwIiBzY3JvbGxpbmc9Im5vIiBzcmM9Imh0dHBzOi8vbG9naW4uc3RhZHRyYWRlbG4uZGUvc3BlY2lhbHMvcmFkZWxtZXRlci90ZWFtLzM1NzUyP0w9MCI+PC9pZnJhbWU+\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">You are currently viewing a placeholder content from <strong>Default<\/strong>. To access the actual content, click the button below. Please note that doing so will share data with third-party providers.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Unblock content<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Accept required service and unblock content<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">More Information<\/a> <\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Auch in diesem Jahr macht die Lebenshilfe Osterholz wieder beim STADTRADELN mit \u2013 f\u00fcr mehr Klimaschutz, bessere Gesundheit und eine starke Gemeinschaft! Gemeinsam sammeln wir Kilometer auf dem Fahrrad und setzen ein Zeichen f\u00fcr nachhaltige Mobilit\u00e4t. Jeder geradelte Kilometer z\u00e4hlt \u2013 egal ob auf dem Weg zur Arbeit, in der Freizeit oder bei gemeinsamen Aktionen.","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2019","post","type-post","status-publish","format-gallery","hentry","category-lebenshilfe","post_format-post-format-gallery"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wir sind beim STADTRADELN dabei! | Lebenshilfe Osterholz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lebenshilfe-ohz.de\/wir-sind-beim-stadtradeln-dabei\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wir sind beim STADTRADELN dabei! | Lebenshilfe Osterholz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lebenshilfe-ohz.de\/wir-sind-beim-stadtradeln-dabei\/\" \/>\n<meta property=\"og:site_name\" content=\"Lebenshilfe Osterholz\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T09:48:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T10:04:17+00:00\" \/>\n<meta name=\"author\" content=\"Ilkme\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ilkme\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/wir-sind-beim-stadtradeln-dabei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/wir-sind-beim-stadtradeln-dabei\\\/\"},\"author\":{\"name\":\"Ilkme\",\"@id\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/#\\\/schema\\\/person\\\/762d060c4d3edc60daa2cd7fdf4c81cc\"},\"headline\":\"Wir sind beim STADTRADELN dabei!\",\"datePublished\":\"2026-05-13T09:48:17+00:00\",\"dateModified\":\"2026-05-13T10:04:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/wir-sind-beim-stadtradeln-dabei\\\/\"},\"wordCount\":142,\"articleSection\":[\"Lebenshilfe\"],\"inLanguage\":\"de-LS\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/wir-sind-beim-stadtradeln-dabei\\\/\",\"url\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/wir-sind-beim-stadtradeln-dabei\\\/\",\"name\":\"Wir sind beim STADTRADELN dabei! | Lebenshilfe Osterholz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/#website\"},\"datePublished\":\"2026-05-13T09:48:17+00:00\",\"dateModified\":\"2026-05-13T10:04:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/#\\\/schema\\\/person\\\/762d060c4d3edc60daa2cd7fdf4c81cc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/wir-sind-beim-stadtradeln-dabei\\\/#breadcrumb\"},\"inLanguage\":\"de-LS\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/wir-sind-beim-stadtradeln-dabei\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/wir-sind-beim-stadtradeln-dabei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/leicht\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wir sind beim STADTRADELN dabei!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/#website\",\"url\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/\",\"name\":\"Lebenshilfe Osterholz\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-LS\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lebenshilfe-ohz.de\\\/#\\\/schema\\\/person\\\/762d060c4d3edc60daa2cd7fdf4c81cc\",\"name\":\"Ilkme\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wir sind beim STADTRADELN dabei! | Lebenshilfe Osterholz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lebenshilfe-ohz.de\/wir-sind-beim-stadtradeln-dabei\/","og_locale":"de_DE","og_type":"article","og_title":"Wir sind beim STADTRADELN dabei! | Lebenshilfe Osterholz","og_url":"https:\/\/www.lebenshilfe-ohz.de\/wir-sind-beim-stadtradeln-dabei\/","og_site_name":"Lebenshilfe Osterholz","article_published_time":"2026-05-13T09:48:17+00:00","article_modified_time":"2026-05-13T10:04:17+00:00","author":"Ilkme","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ilkme","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lebenshilfe-ohz.de\/wir-sind-beim-stadtradeln-dabei\/#article","isPartOf":{"@id":"https:\/\/www.lebenshilfe-ohz.de\/wir-sind-beim-stadtradeln-dabei\/"},"author":{"name":"Ilkme","@id":"https:\/\/www.lebenshilfe-ohz.de\/#\/schema\/person\/762d060c4d3edc60daa2cd7fdf4c81cc"},"headline":"Wir sind beim STADTRADELN dabei!","datePublished":"2026-05-13T09:48:17+00:00","dateModified":"2026-05-13T10:04:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lebenshilfe-ohz.de\/wir-sind-beim-stadtradeln-dabei\/"},"wordCount":142,"articleSection":["Lebenshilfe"],"inLanguage":"de-LS"},{"@type":"WebPage","@id":"https:\/\/www.lebenshilfe-ohz.de\/wir-sind-beim-stadtradeln-dabei\/","url":"https:\/\/www.lebenshilfe-ohz.de\/wir-sind-beim-stadtradeln-dabei\/","name":"Wir sind beim STADTRADELN dabei! | Lebenshilfe Osterholz","isPartOf":{"@id":"https:\/\/www.lebenshilfe-ohz.de\/#website"},"datePublished":"2026-05-13T09:48:17+00:00","dateModified":"2026-05-13T10:04:17+00:00","author":{"@id":"https:\/\/www.lebenshilfe-ohz.de\/#\/schema\/person\/762d060c4d3edc60daa2cd7fdf4c81cc"},"breadcrumb":{"@id":"https:\/\/www.lebenshilfe-ohz.de\/wir-sind-beim-stadtradeln-dabei\/#breadcrumb"},"inLanguage":"de-LS","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lebenshilfe-ohz.de\/wir-sind-beim-stadtradeln-dabei\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lebenshilfe-ohz.de\/wir-sind-beim-stadtradeln-dabei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lebenshilfe-ohz.de\/leicht\/"},{"@type":"ListItem","position":2,"name":"Wir sind beim STADTRADELN dabei!"}]},{"@type":"WebSite","@id":"https:\/\/www.lebenshilfe-ohz.de\/#website","url":"https:\/\/www.lebenshilfe-ohz.de\/","name":"Lebenshilfe Osterholz","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lebenshilfe-ohz.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-LS"},{"@type":"Person","@id":"https:\/\/www.lebenshilfe-ohz.de\/#\/schema\/person\/762d060c4d3edc60daa2cd7fdf4c81cc","name":"Ilkme"}]}},"_links":{"self":[{"href":"https:\/\/www.lebenshilfe-ohz.de\/leicht\/wp-json\/wp\/v2\/posts\/2019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebenshilfe-ohz.de\/leicht\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebenshilfe-ohz.de\/leicht\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebenshilfe-ohz.de\/leicht\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebenshilfe-ohz.de\/leicht\/wp-json\/wp\/v2\/comments?post=2019"}],"version-history":[{"count":7,"href":"https:\/\/www.lebenshilfe-ohz.de\/leicht\/wp-json\/wp\/v2\/posts\/2019\/revisions"}],"predecessor-version":[{"id":2026,"href":"https:\/\/www.lebenshilfe-ohz.de\/leicht\/wp-json\/wp\/v2\/posts\/2019\/revisions\/2026"}],"wp:attachment":[{"href":"https:\/\/www.lebenshilfe-ohz.de\/leicht\/wp-json\/wp\/v2\/media?parent=2019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebenshilfe-ohz.de\/leicht\/wp-json\/wp\/v2\/categories?post=2019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebenshilfe-ohz.de\/leicht\/wp-json\/wp\/v2\/tags?post=2019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}